{"id":5501,"date":"2011-06-20T10:25:57","date_gmt":"2011-06-20T09:25:57","guid":{"rendered":"http:\/\/www.loveof74.es\/weblog\/?p=5501"},"modified":"2011-06-20T11:05:52","modified_gmt":"2011-06-20T10:05:52","slug":"tenniscoats-cafe-oto","status":"publish","type":"post","link":"http:\/\/www.loveof74.es\/weblog\/cultura\/conciertos\/tenniscoats-cafe-oto\/","title":{"rendered":"Tenniscoats @CafeOto : Close to you"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignright\" style=\"margin: 3px 15px;\" src=\"http:\/\/www.loveof74.es\/weblog\/wp-content\/uploads\/2011\/06\/tenniscoats_pola_2.jpg\" alt=\"\" width=\"255\" height=\"311\" \/>Nuestra previa al glamoroso arranque del <strong><a href=\"http:\/\/www.diariovasco.com\/v\/20110619\/al-dia-sociedad\/club-reina-gobernador-20110619.html\" target=\"_blank\">torneo de la elegancia<\/a><\/strong> nos pill\u00f3 con la chaqueta de sport bien abotonada. El tiempo cambiante y un paraguas demasiado barato para los usos predispuestos \u2013 traducci\u00f3n: en la papelera a las 8 horas de actividad- nos llevaron, pasito va pasito viene, hasta el<strong> <a href=\"http:\/\/www.cafeoto.co.uk\/\" target=\"_blank\">Caf\u00e9 Oto<\/a><\/strong>.<\/p>\n<p>Un emplazamiento especializado en <strong><a href=\"http:\/\/www.cafeoto.co.uk\/programme.shtm\" target=\"_blank\">m\u00fasicas abiertas<\/a><\/strong>, precioso, muy acogedor, con mesas y sillas dispuestas por toda la sala y una barra de bar que te cierra en los morros en cuanto comienza el concierto. Si \u00absilence is golden\u00bb, la sala deb\u00eda estar llena de petrod\u00f3lares. Nadie abri\u00f3 el pico durante los 90 minutos de show.<\/p>\n<p>Los japoneses Saya &amp; Takashi Ueno, inframundialmente conocidos como Tenniscoats, se plantaron con una formaci\u00f3n de combate, tambi\u00e9n conocida como \u201cHand luggage\u201d o \u201c<strong><a href=\"http:\/\/vimeo.com\/11046286 \" target=\"_blank\">Blogotheque bajo techo<\/a><\/strong>\u201d ): guitarra espa\u00f1ola, teclados de comuni\u00f3n, mel\u00f3dicas y un piano de cola ya presente en el lugar antes de su visita. M\u00e1s que suficiente para encandilar a todos los presentes. \u00a1Vaya concierto m\u00e1s tierno y encantador!<\/p>\n<p>Pase\u00e1ndose sin parar por el bar, adaptando el concepto ambiental de sus canciones (<strong><a href=\"http:\/\/open.spotify.com\/album\/7N2B6SyI45qvNz8leJBWtx\">Tenniscoats \u2013 Temporacha<\/a>,<\/strong> aunque ya tienen un disco nuevo 2011 en la calle) al espacio esc\u00e9nico y con cierto aire improvisado, sus creaciones \u2013repartidas en tres tandas- sonaban m\u00ednimas, esponjosas, repletas de parsimonia, con una contagiosa diversi\u00f3n y alegr\u00eda ejecutante.<\/p>\n<p>El teclado se interpretaba para los cuellos de sus camisas. La ejecuci\u00f3n, basada en progresiones de acordes con pocos cambios m\u00e1s all\u00e1 de sus intensidades y una voz que brincaba sobre ellos, se aderezaba en ocasiones con curiosos encontronazos entre ellos. Ella parec\u00eda querer tocar las cuerdas, o jugar con \u00e9l. Y a\u00fan recuerdo las risas del chico, casi carcajadas, cuando ella corr\u00eda a toda prisa por<strong> <a href=\"http:\/\/www.youtube.com\/user\/geomck#p\/a\/u\/0\/0y2J0KuLeZs\" target=\"_blank\">la versi\u00f3n de Burt Bacharach<\/a> <\/strong>que interpretaron. O el momento en que su macarr\u00f3nico ingl\u00e9s intentaba decir \u201cThis song\u201d. Sin olvidar la traducci\u00f3n simultanea de una canci\u00f3n ofrecida por el guitarrista.<\/p>\n<p>Quiz\u00e1s por el occidentalismo que sufrimos, pero la primera raci\u00f3n de melod\u00edas pudo ser una mezcla entre el pop, <strong><a href=\"http:\/\/www.youtube.com\/watch?v=WAOjgXhSWIk\" target=\"_blank\">las nanas<\/a><\/strong> y los cantares tradicionales japoneses, la cara AA y ac\u00fastica del <strong><a href=\"http:\/\/open.spotify.com\/album\/3D3NbUl0o2LFY7eqU2P4eo\">Two Sunsets<\/a><\/strong> que firmaron a medias con The Pastels (con acentos en la \u00e9, que se dice as\u00ed, oyes). Demostrando un estado superior a la hora de componer que el resto de seudo creadores. No solo por demostrar conocimientos a la hora de tocar el piano y realizar dibujines casi infantiles, sino por saber transmitir seductoras emociones escapando de las estructuraciones tradicionales.<\/p>\n<p>El sosiego se mantuvo pleno de inter\u00e9s hasta el final, salvo dos A\u00daN M\u00c1S GLORIOSAS excepciones de marcado caracter popero (<strong><a href=\"http:\/\/www.youtube.com\/watch?v=ZwnpIEjI1sU\" target=\"_blank\">\u00e9sta, una de ellas. IMPRESIONANTE, PELOS DE PUNTA<\/a><\/strong>) que perdonar\u00e1n no identifique porque no tengo ni pajolera idea de sus t\u00edtulos. Celebramos la \u00faltima nota del <em>encore<\/em>, sonrisa gigante mediante, con un tempranillo a precio de Bodega de Arzak y la compra de <strong><a href=\"http:\/\/userserve-ak.last.fm\/serve\/126\/61653919.jpg \" target=\"_blank\">un souvenir m\u00e1s tarde autografiado<\/a> <\/strong>para no olvidar jam\u00e1s ese momento tan celestial como enamoradizo y maravilloso.<\/p>\n<p><strong><a href=\"http:\/\/www.youtube.com\/watch?v=q0AWwKUn5UE\" target=\"_blank\">Baibaa ba bimbaaa, niii baba buuuuu<\/a><\/strong>&#8230;<\/p>\n<p>[La foto es del <strong><a href=\"http:\/\/www.flickr.com\/photos\/cafeoto\" target=\"_blank\">flickr de la sala<\/a><\/strong>. Tiene todos los derechos reservados, pero nos permitimos hacer una versi\u00f3n de la misma. Hey, colegas, que son m\u00fasicas abiertas, hombre]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestra previa al glamoroso arranque del torneo de la elegancia nos pill\u00f3 con la chaqueta de sport bien abotonada. El tiempo cambiante y un paraguas demasiado barato para los usos predispuestos \u2013 traducci\u00f3n: en la papelera a las 8 horas de actividad- nos llevaron, pasito va pasito viene, hasta el Caf\u00e9 Oto. Un emplazamiento especializado &#8230; <a title=\"Tenniscoats @CafeOto : Close to you\" class=\"read-more\" href=\"http:\/\/www.loveof74.es\/weblog\/cultura\/conciertos\/tenniscoats-cafe-oto\/\" aria-label=\"M\u00e1s en Tenniscoats @CafeOto : Close to you\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_mi_skip_tracking":false},"categories":[31],"tags":[],"aioseo_notices":[],"views":4156,"_links":{"self":[{"href":"http:\/\/www.loveof74.es\/weblog\/wp-json\/wp\/v2\/posts\/5501"}],"collection":[{"href":"http:\/\/www.loveof74.es\/weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.loveof74.es\/weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.loveof74.es\/weblog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.loveof74.es\/weblog\/wp-json\/wp\/v2\/comments?post=5501"}],"version-history":[{"count":31,"href":"http:\/\/www.loveof74.es\/weblog\/wp-json\/wp\/v2\/posts\/5501\/revisions"}],"predecessor-version":[{"id":5507,"href":"http:\/\/www.loveof74.es\/weblog\/wp-json\/wp\/v2\/posts\/5501\/revisions\/5507"}],"wp:attachment":[{"href":"http:\/\/www.loveof74.es\/weblog\/wp-json\/wp\/v2\/media?parent=5501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.loveof74.es\/weblog\/wp-json\/wp\/v2\/categories?post=5501"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.loveof74.es\/weblog\/wp-json\/wp\/v2\/tags?post=5501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}